{"id":2707,"date":"2017-12-11T10:19:45","date_gmt":"2017-12-11T09:19:45","guid":{"rendered":"https:\/\/www.hotelambasciatoricattolica.it\/ristorante\/"},"modified":"2022-06-23T15:17:33","modified_gmt":"2022-06-23T13:17:33","slug":"restaurant","status":"publish","type":"page","link":"https:\/\/www.hotelambasciatoricattolica.it\/fr\/restaurant\/","title":{"rendered":"H\u00f4tels avec restaurant \u00e0 Cattolica avec cuisine local"},"content":{"rendered":"<h2>Nous servons les plaisirs et les saveurs de la Romagne, tous rigoureusement pr\u00e9par\u00e9s par typiques mini experts Romagne<\/h2>\n<h3>Bonjour commence le matin!<\/h3>\n<p>Nous aimons vous g\u00e2ter d\u00e8s les premi\u00e8res heures de la journ\u00e9e, pour cette raison sera attendent <strong>croissants, des biscuits et des g\u00e2teaux faits maison<\/strong>, confitures, chocolat, yaourts, c\u00e9r\u00e9ales, jus de fruits et bien plus encore. Sans oublier le <strong>caf\u00e9 italien traditionnel et des boissons sont exclusivement avec du lait et de caf\u00e9 en grains<\/strong>.<\/p>\n<div id='gallery-1' class='gallery galleryid-2707 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-colazione-salato-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-colazione-salato-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-colazione-salato-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-colazione-salato-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-colazione-salato-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-colazione-salato-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-colazione-salato-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-colazione-salato-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-colazione-buffet-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-colazione-buffet-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-colazione-buffet-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-colazione-buffet-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-colazione-buffet-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-colazione-buffet-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-colazione-buffet-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-colazione-buffet-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-colazione-buffet-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-colazione-buffet-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-colazione-buffet-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-colazione-buffet-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-colazione-buffet-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-colazione-buffet-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-colazione-buffet-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-colazione-buffet-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-colazione-buffet-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-colazione-buffet-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-colazione-buffet-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-colazione-buffet-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-colazione-buffet-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-colazione-buffet-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-colazione-buffet-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-colazione-buffet-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-colazione-bomboloni-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-colazione-bomboloni-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-colazione-bomboloni-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-colazione-bomboloni-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-colazione-bomboloni-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-colazione-bomboloni-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-colazione-bomboloni-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-colazione-bomboloni-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-colazione-cereali-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-colazione-cereali-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-colazione-cereali-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-colazione-cereali-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-colazione-cereali-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-colazione-cereali-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-colazione-cereali-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-colazione-cereali-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-colazione-crepes-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-colazione-crepes-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-colazione-crepes-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-colazione-crepes-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-colazione-crepes-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-colazione-crepes-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-colazione-crepes-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-colazione-crepes-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-colazione-tavolo-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-colazione-tavolo-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-colazione-tavolo-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-colazione-tavolo-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-colazione-tavolo-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-colazione-tavolo-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-colazione-tavolo-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-colazione-tavolo-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<h3>Apr\u00e8s la mer \u2026 tr\u00e8s faim! Avoir un si\u00e8ge \u00e0 la table \u2026<\/h3>\n<p>Chaque jour, au d\u00e9jeuner et au d\u00eener, vous vous attendez \u00e0 un riche<strong> buffet de hors-d\u2019\u0153uvre et l\u00e9gumes<\/strong>, o\u00f9 sera <strong>notre pain maison<\/strong>: vous pouvez directement choisir ce que vous d\u2019abord appr\u00e9ci\u00e9, mettre \u00e0 l\u2019aise \u00e0 la table et, comme l\u2019app\u00e9tit vient en mangeant, vous pouvez choisir n\u2019importe quel jour \u00e0 partir de <strong>3 menu diff\u00e9rent de viande ou de poisson pour le d\u00e9jeuner et le d\u00eener!<\/strong> Les plats qui pr\u00e9f\u00e8rent, seront servis \u00e0 la table parce que nous pensons qu\u2019au moins en vacances est agr\u00e9able d\u2019\u00eatre servi! Il y aura, pour conclure de la meilleure fa\u00e7on, <strong>buffet de fruits frais au d\u00e9jeuner et un dessert au d\u00eener<\/strong>.<\/p>\n<div id='gallery-2' class='gallery galleryid-2707 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/19-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/19-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/19-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/19-ristorante-aperitivo-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/19-ristorante-aperitivo-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/19-ristorante-aperitivo-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/19-ristorante-aperitivo-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/19-ristorante-aperitivo-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/20-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/20-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/20-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/20-ristorante-aperitivo-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/20-ristorante-aperitivo-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/20-ristorante-aperitivo-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/20-ristorante-aperitivo-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/20-ristorante-aperitivo-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/21-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/21-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/21-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/21-ristorante-aperitivo-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/21-ristorante-aperitivo-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/21-ristorante-aperitivo-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/21-ristorante-aperitivo-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/21-ristorante-aperitivo-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/18-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/18-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/18-ristorante-aperitivo-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/18-ristorante-aperitivo-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/18-ristorante-aperitivo-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/18-ristorante-aperitivo-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/18-ristorante-aperitivo-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/18-ristorante-aperitivo-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<h3>D\u00eener sur la base romagnole piadina typiques \u2026<\/h3>\n<p>Nous sommes en Romagne, la terre de la bonne nourriture et la <strong>piadina<\/strong>, <strong>tous les mercredis<\/strong>, nos serveurs seront pr\u00eats \u00e0 vous faire d\u00e9guster un <strong>d\u00eener Romagne typique<\/strong> avec piadina accompagn\u00e9 de viandes savoureuses, p\u00e2tes avec sauce \u00e0 la viande et cochon de lait r\u00f4ti dans \u2026 \u00e0 l\u00e9cher moustaches!<\/p>\n<div id='gallery-3' class='gallery galleryid-2707 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-ristorante-piadina-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-ristorante-piadina-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-ristorante-piadina-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-ristorante-piadina-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-ristorante-piadina-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-ristorante-piadina-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-ristorante-piadina-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/4-ristorante-piadina-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-ristorante-piadina-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-ristorante-piadina-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-ristorante-piadina-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-ristorante-piadina-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-ristorante-piadina-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-ristorante-piadina-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-ristorante-piadina-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/5-ristorante-piadina-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-ristorante-piadina-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-ristorante-piadina-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-ristorante-piadina-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-ristorante-piadina-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-ristorante-piadina-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-ristorante-piadina-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-ristorante-piadina-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/6-ristorante-piadina-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-ristorante-piadina-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-ristorante-piadina-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-ristorante-piadina-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-ristorante-piadina-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-ristorante-piadina-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-ristorante-piadina-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-ristorante-piadina-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/7-ristorante-piadina-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/11-ristorante-piatto-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/11-ristorante-piatto-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/11-ristorante-piatto-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/11-ristorante-piatto-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/11-ristorante-piatto-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/11-ristorante-piatto-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/11-ristorante-piatto-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/11-ristorante-piatto-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<h3>D\u00eener de Gala<\/h3>\n<p>Ceci est Romagne, Romagne est non seulement la terre de piadina, mais aussi un lieu de mer, puis, si vous \u00eates un amateur de bon poisson, nous allons vous aider \u00e0 concevoir <strong>une soir\u00e9e avec un menu sp\u00e9cial de poisson ou de viande<\/strong>. Et de conclure, de la <strong>bonne musique en direct pour adultes et enfants<\/strong>.<\/p>\n<div id='gallery-4' class='gallery galleryid-2707 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-ristorante-passatelli-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-ristorante-passatelli-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-ristorante-passatelli-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-ristorante-passatelli-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-ristorante-passatelli-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-ristorante-passatelli-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-ristorante-passatelli-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/8-ristorante-passatelli-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/9-ristorante-passatelli-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/9-ristorante-passatelli-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/9-ristorante-passatelli-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/9-ristorante-passatelli-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/9-ristorante-passatelli-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/9-ristorante-passatelli-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/9-ristorante-passatelli-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/9-ristorante-passatelli-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/13-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/13-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/13-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/13-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/13-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/13-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/13-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/13-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/14-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/14-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/14-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/14-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/14-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/14-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/14-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/14-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/15-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/15-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/15-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/15-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/15-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/15-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/15-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/15-ristorante-spaghetti-vongole-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/16-ristorante-filetto-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/16-ristorante-filetto-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/16-ristorante-filetto-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/16-ristorante-filetto-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/16-ristorante-filetto-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/16-ristorante-filetto-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/16-ristorante-filetto-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/16-ristorante-filetto-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/17-ristorante-filetto-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/17-ristorante-filetto-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/17-ristorante-filetto-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/17-ristorante-filetto-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/17-ristorante-filetto-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/17-ristorante-filetto-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/17-ristorante-filetto-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/17-ristorante-filetto-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-ristorante-panefresco-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-ristorante-panefresco-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-ristorante-panefresco-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-ristorante-panefresco-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-ristorante-panefresco-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-ristorante-panefresco-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-ristorante-panefresco-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/3-ristorante-panefresco-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/10-ristorante-piatto-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/10-ristorante-piatto-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/10-ristorante-piatto-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/10-ristorante-piatto-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/10-ristorante-piatto-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/10-ristorante-piatto-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/10-ristorante-piatto-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/10-ristorante-piatto-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/12-ristorante-piatto-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/12-ristorante-piatto-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/12-ristorante-piatto-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/12-ristorante-piatto-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/12-ristorante-piatto-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/12-ristorante-piatto-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/12-ristorante-piatto-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/12-ristorante-piatto-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-ristorante-vista-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-ristorante-vista-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-ristorante-vista-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-ristorante-vista-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-ristorante-vista-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-ristorante-vista-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-ristorante-vista-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/1-ristorante-vista-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-ristorante-vista-hotel-ambasciatori-cattolica.jpg' data-size=\"1000x700\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-ristorante-vista-hotel-ambasciatori-cattolica.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-ristorante-vista-hotel-ambasciatori-cattolica.jpg 1000w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-ristorante-vista-hotel-ambasciatori-cattolica-768x538.jpg 768w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-ristorante-vista-hotel-ambasciatori-cattolica-57x40.jpg 57w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-ristorante-vista-hotel-ambasciatori-cattolica-72x50.jpg 72w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-ristorante-vista-hotel-ambasciatori-cattolica-114x80.jpg 114w, https:\/\/www.hotelambasciatoricattolica.it\/wp-content\/uploads\/2022\/06\/2-ristorante-vista-hotel-ambasciatori-cattolica-144x101.jpg 144w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<h3>Une cuisine pour tous \u2026<\/h3>\n<p>Nous sommes conscients que, aujourd\u2019hui, beaucoup de gens sont constamment confront\u00e9 au probl\u00e8me de l\u2019<strong>intol\u00e9rance alimentaire<\/strong> ou de la <strong>\u00ab maladie coeliaque,\u00a0<\/strong> pour eux, <strong>notre chef vous pr\u00e9parera des plats sp\u00e9ciaux<\/strong> avec soin<strong> mais sans sacrifier le go\u00fbt<\/strong> \u2026 Afin d\u2019assurer un service ad\u00e9quat pour le type de probl\u00e8me, nous demandons \u00e0 nos clients de communiquer, d\u00e9j\u00e0 au moment de la r\u00e9servation, des probl\u00e8mes ou des intol\u00e9rances alimentaires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous servons les plaisirs et les saveurs de la Romagne, tous rigoureusement pr\u00e9par\u00e9s par typiques mini experts Romagne Bonjour commence le matin! Nous aimons vous g\u00e2ter d\u00e8s les premi\u00e8res heures de la journ\u00e9e, pour cette raison sera attendent croissants, des biscuits et des g\u00e2teaux faits maison, confitures, chocolat, yaourts, c\u00e9r\u00e9ales, jus de fruits et bien plus encore. Sans oublier le caf\u00e9 italien traditionnel et des boissons sont exclusivement avec du &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-2707","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hotelambasciatoricattolica.it\/fr\/wp-json\/wp\/v2\/pages\/2707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelambasciatoricattolica.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelambasciatoricattolica.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelambasciatoricattolica.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelambasciatoricattolica.it\/fr\/wp-json\/wp\/v2\/comments?post=2707"}],"version-history":[{"count":0,"href":"https:\/\/www.hotelambasciatoricattolica.it\/fr\/wp-json\/wp\/v2\/pages\/2707\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hotelambasciatoricattolica.it\/fr\/wp-json\/wp\/v2\/media?parent=2707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}